{"id":71380,"date":"2026-09-01T10:06:18","date_gmt":"2026-09-01T08:06:18","guid":{"rendered":"https:\/\/www.lesaka.eus\/?post_type=eventos&#038;p=71380"},"modified":"2026-09-01T10:07:07","modified_gmt":"2026-09-01T08:07:07","slug":"gure-zirkua-en-lesaka","status":"publish","type":"eventos","link":"https:\/\/www.lesaka.eus\/es\/eventos\/gure-zirkua-en-lesaka\/","title":{"rendered":"Gure Zirkua en Lesaka"},"content":{"rendered":"<p><a href=\"https:\/\/www.gurezirkua.eus\/producto\/lesaka\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-71376\" src=\"https:\/\/www.lesaka.eus\/wp-content\/uploads\/2026\/09\/TIKETAK-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.lesaka.eus\/wp-content\/uploads\/2026\/09\/TIKETAK-300x300.jpg 300w, https:\/\/www.lesaka.eus\/wp-content\/uploads\/2026\/09\/TIKETAK-150x150.jpg 150w, https:\/\/www.lesaka.eus\/wp-content\/uploads\/2026\/09\/TIKETAK-115x115.jpg 115w, https:\/\/www.lesaka.eus\/wp-content\/uploads\/2026\/09\/TIKETAK-350x350.jpg 350w, https:\/\/www.lesaka.eus\/wp-content\/uploads\/2026\/09\/TIKETAK-450x450.jpg 450w, https:\/\/www.lesaka.eus\/wp-content\/uploads\/2026\/09\/TIKETAK.jpg 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"featured_media":71379,"template":"","meta":{"_wpml_word_count":["{\"total\":0,\"to_translate\":{\"eu\":2,\"es\":2}}"],"_edit_lock":["1788249891:5"],"_edit_last":["5"],"barra":[""],"dias":[";11-9-2026;12-9-2026;13-9-2026;18-9-2026;19-9-2026;20-9-2026;25-9-2026;26-9-2026;"],"event_date":["1789084800"],"event_date1":["1790380800"],"event_horario_fin":[""],"event_horario_inicio":[""],"imagenslia":[""],"autor_o":[""],"boton1":[""],"boton1u":[""],"event_ext":[""],"event_horario":[""],"event_location":["Lesaka"],"fechas":[""],"importe":[""],"inscripcion":[""],"nota":[""],"ponente":[""],"_thumbnail_id":["71379"],"botonve":[""],"botonveu":[""],"mostrar_barra":["1"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_yoast_wpseo_primary_categoriaeventos":["256"],"_yoast_wpseo_estimated-reading-time-minutes":["1"]},"class_list":["post-71380","eventos","type-eventos","status-publish","has-post-thumbnail","hentry","categoriaeventos-antzerkia-es","categoriaeventos-boletin"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>Gure Zirkua en Lesaka - Lesakako Udala<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.lesaka.eus\/es\/eventos\/gure-zirkua-en-lesaka\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Gure Zirkua en Lesaka - Lesakako Udala\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.lesaka.eus\/es\/eventos\/gure-zirkua-en-lesaka\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Lesakako Udala\" \/>\r\n<meta property=\"article:modified_time\" content=\"2026-09-01T08:07:07+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.lesaka.eus\/wp-content\/uploads\/2026\/09\/logoa_GZ.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\r\n\t<meta property=\"og:image:height\" content=\"550\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lesaka.eus\/es\/eventos\/gure-zirkua-en-lesaka\/\",\"url\":\"https:\/\/www.lesaka.eus\/es\/eventos\/gure-zirkua-en-lesaka\/\",\"name\":\"Gure Zirkua en Lesaka - Lesakako Udala\",\"isPartOf\":{\"@id\":\"https:\/\/www.lesaka.eus\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lesaka.eus\/es\/eventos\/gure-zirkua-en-lesaka\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lesaka.eus\/es\/eventos\/gure-zirkua-en-lesaka\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lesaka.eus\/wp-content\/uploads\/2026\/09\/logoa_GZ.png\",\"datePublished\":\"2026-09-01T08:06:18+00:00\",\"dateModified\":\"2026-09-01T08:07:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lesaka.eus\/es\/eventos\/gure-zirkua-en-lesaka\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lesaka.eus\/es\/eventos\/gure-zirkua-en-lesaka\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.lesaka.eus\/es\/eventos\/gure-zirkua-en-lesaka\/#primaryimage\",\"url\":\"https:\/\/www.lesaka.eus\/wp-content\/uploads\/2026\/09\/logoa_GZ.png\",\"contentUrl\":\"https:\/\/www.lesaka.eus\/wp-content\/uploads\/2026\/09\/logoa_GZ.png\",\"width\":1000,\"height\":550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lesaka.eus\/es\/eventos\/gure-zirkua-en-lesaka\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.lesaka.eus\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ekitaldiak\",\"item\":\"https:\/\/www.lesaka.eus\/eventos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gure Zirkua en Lesaka\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lesaka.eus\/#website\",\"url\":\"https:\/\/www.lesaka.eus\/\",\"name\":\"Lesakako Udala\",\"description\":\"Lesaka ZUBIAK ERAIKIZ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lesaka.eus\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gure Zirkua en Lesaka - Lesakako Udala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesaka.eus\/es\/eventos\/gure-zirkua-en-lesaka\/","og_locale":"es_ES","og_type":"article","og_title":"Gure Zirkua en Lesaka - Lesakako Udala","og_url":"https:\/\/www.lesaka.eus\/es\/eventos\/gure-zirkua-en-lesaka\/","og_site_name":"Lesakako Udala","article_modified_time":"2026-09-01T08:07:07+00:00","og_image":[{"width":1000,"height":550,"url":"https:\/\/www.lesaka.eus\/wp-content\/uploads\/2026\/09\/logoa_GZ.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lesaka.eus\/es\/eventos\/gure-zirkua-en-lesaka\/","url":"https:\/\/www.lesaka.eus\/es\/eventos\/gure-zirkua-en-lesaka\/","name":"Gure Zirkua en Lesaka - Lesakako Udala","isPartOf":{"@id":"https:\/\/www.lesaka.eus\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesaka.eus\/es\/eventos\/gure-zirkua-en-lesaka\/#primaryimage"},"image":{"@id":"https:\/\/www.lesaka.eus\/es\/eventos\/gure-zirkua-en-lesaka\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lesaka.eus\/wp-content\/uploads\/2026\/09\/logoa_GZ.png","datePublished":"2026-09-01T08:06:18+00:00","dateModified":"2026-09-01T08:07:07+00:00","breadcrumb":{"@id":"https:\/\/www.lesaka.eus\/es\/eventos\/gure-zirkua-en-lesaka\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesaka.eus\/es\/eventos\/gure-zirkua-en-lesaka\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.lesaka.eus\/es\/eventos\/gure-zirkua-en-lesaka\/#primaryimage","url":"https:\/\/www.lesaka.eus\/wp-content\/uploads\/2026\/09\/logoa_GZ.png","contentUrl":"https:\/\/www.lesaka.eus\/wp-content\/uploads\/2026\/09\/logoa_GZ.png","width":1000,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesaka.eus\/es\/eventos\/gure-zirkua-en-lesaka\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.lesaka.eus\/"},{"@type":"ListItem","position":2,"name":"Ekitaldiak","item":"https:\/\/www.lesaka.eus\/eventos\/"},{"@type":"ListItem","position":3,"name":"Gure Zirkua en Lesaka"}]},{"@type":"WebSite","@id":"https:\/\/www.lesaka.eus\/#website","url":"https:\/\/www.lesaka.eus\/","name":"Lesakako Udala","description":"Lesaka ZUBIAK ERAIKIZ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesaka.eus\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.lesaka.eus\/es\/wp-json\/wp\/v2\/eventos\/71380"}],"collection":[{"href":"https:\/\/www.lesaka.eus\/es\/wp-json\/wp\/v2\/eventos"}],"about":[{"href":"https:\/\/www.lesaka.eus\/es\/wp-json\/wp\/v2\/types\/eventos"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesaka.eus\/es\/wp-json\/wp\/v2\/media\/71379"}],"wp:attachment":[{"href":"https:\/\/www.lesaka.eus\/es\/wp-json\/wp\/v2\/media?parent=71380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}